{"id":1946,"date":"2022-11-25T14:21:19","date_gmt":"2022-11-25T13:21:19","guid":{"rendered":"https:\/\/aidaballmann.com\/filmografia_\/malviviendo\/"},"modified":"2023-02-11T23:02:50","modified_gmt":"2023-02-11T22:02:50","slug":"malviviendo","status":"publish","type":"filmografia_","link":"https:\/\/aidaballmann.com\/de\/filmografia_\/malviviendo\/","title":{"rendered":"Malviviendo"},"featured_media":2084,"template":"","genero":[1179],"tipo":[27],"class_list":["post-1946","filmografia_","type-filmografia_","status-publish","has-post-thumbnail","hentry","genero-komodie","tipo-serie-de"],"_links":{"self":[{"href":"https:\/\/aidaballmann.com\/de\/wp-json\/wp\/v2\/filmografia_\/1946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aidaballmann.com\/de\/wp-json\/wp\/v2\/filmografia_"}],"about":[{"href":"https:\/\/aidaballmann.com\/de\/wp-json\/wp\/v2\/types\/filmografia_"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aidaballmann.com\/de\/wp-json\/wp\/v2\/media\/2084"}],"wp:attachment":[{"href":"https:\/\/aidaballmann.com\/de\/wp-json\/wp\/v2\/media?parent=1946"}],"wp:term":[{"taxonomy":"genero","embeddable":true,"href":"https:\/\/aidaballmann.com\/de\/wp-json\/wp\/v2\/genero?post=1946"},{"taxonomy":"tipo","embeddable":true,"href":"https:\/\/aidaballmann.com\/de\/wp-json\/wp\/v2\/tipo?post=1946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}